﻿{"id":583,"date":"2026-05-13T16:31:34","date_gmt":"2026-05-13T08:31:34","guid":{"rendered":"https:\/\/www.bihec.com\/charles\/?p=583"},"modified":"2026-05-13T16:31:34","modified_gmt":"2026-05-13T08:31:34","slug":"%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/","title":{"rendered":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94"},"content":{"rendered":"<h2><strong>\u7f8e\u56fd\u539f\u88c5 <a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles-supper\/\" title=\"View all posts in Charles Supper\" target=\"_blank\">Charles Supper<\/a> <a href=\"https:\/\/www.bihec.com\/charles\/tag\/15-qz-1-5-mm\/\" title=\"View all posts in 15-QZ-1.5 mm\" target=\"_blank\">15-QZ-1.5 mm<\/a> <a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a> \u73b0\u8d27\u4f9b\u5e94<\/strong><\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-533\" src=\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\u5c4f\u5e55\u622a\u56fe-2025-12-25-153014-1-300x244.png\" alt=\"\" width=\"300\" height=\"244\" \/><\/p>\n<p>\u7528\u4e8eX\u5c04\u7ebf\u884d\u5c04\u7684<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\u2014\u2014<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1\/\" title=\"View all posts in \u77f3\u82f1\" target=\"_blank\">\u77f3\u82f1<\/a>\uff08<a href=\"https:\/\/www.bihec.com\/charles\/tag\/qz\/\" title=\"View all posts in QZ\" target=\"_blank\">QZ<\/a>\uff09<\/p>\n<p><a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles\/\" title=\"View all posts in Charles\" target=\"_blank\">Charles<\/a> Supper\u516c\u53f8\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50\u5168\u7684<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e8%96%84%e5%a3%81\/\" title=\"View all posts in \u8584\u58c1\" target=\"_blank\">\u8584\u58c1<\/a><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u6bdb\u7ec6\u7ba1<\/a>\uff0c\u89c4\u683c\u6db5\u76d6\u5916\u5f840.1\u6beb\u7c73\u81f35.0\u6beb\u7c73\uff0c\u6750\u8d28\u5305\u62ec<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%89%b9%e7%a7%8d%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u7279\u79cd\u73bb\u7483\" target=\"_blank\">\u7279\u79cd\u73bb\u7483<\/a>\u3001<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%8c%e7%a1%bc%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u5bcc\u787c\u73bb\u7483\" target=\"_blank\">\u5bcc\u787c\u73bb\u7483<\/a>\u53ca\u77f3\u82f1\u3002<\/p>\n<p>\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1\u89c4\u683c\uff1a<\/p>\n<p>\u77f3\u82f1 01-QZ &#8211; 0.1mm<br \/>\n\u77f3\u82f1 02-QZ &#8211; 0.2mm<br \/>\n\u77f3\u82f1 03-QZ &#8211; 0.3mm<br \/>\n\u77f3\u82f1 04-QZ &#8211; 0.4mm<br \/>\n\u77f3\u82f1 05-QZ &#8211; 0.5 mm<br \/>\n\u77f3\u82f1 06-QZ &#8211; 0.6 mm<br \/>\n\u77f3\u82f1 07-QZ &#8211; 0.7 mm<br \/>\n\u77f3\u82f1 08-QZ &#8211; 0.8mm<br \/>\n\u77f3\u82f1 09-QZ &#8211; 0.9mm<br \/>\n\u77f3\u82f1 10-QZ &#8211; 1.0mm<br \/>\n\u77f3\u82f1 15-QZ &#8211; 1.5mm<br \/>\n\u77f3\u82f1 20-QZ &#8211; 2.0mm<br \/>\n\u77f3\u82f1 25-QZ &#8211; 2.5mm<br \/>\n\u77f3\u82f1 30-QZ &#8211; 3.0mm<br \/>\n\u77f3\u82f1 40-QZ &#8211; 4.0mm<\/p>\n<p>\u7279\u79cd\u73bb\u7483 (<a href=\"https:\/\/www.bihec.com\/charles\/tag\/sg\/\" title=\"View all posts in SG\" target=\"_blank\">SG<\/a>) \u25c6 <a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%8c%e7%a1%bc\/\" title=\"View all posts in \u5bcc\u787c\" target=\"_blank\">\u5bcc\u787c<\/a>\u73bb\u7483 (BG) \u25c6 \u77f3\u82f1\u73bb\u7483 (QZ) \u29bf \u77f3\u82f1\u73bb\u7483 (SQZ) \u25c6 \u77f3\u82f1\u73bb\u7483 (OQZ) \u25c6 \u77f3\u82f1\u73bb\u7483 (40SQZ) \u25c6 \u77f3\u82f1\u73bb\u7483 (40OQZ) \u25c6<br \/>\n\u4e3aCharles Supper\u6309\u9ad8\u6807\u51c6\u5236\u9020\u3002<br \/>\n\u6807\u51c6\u73bb\u7483\u6280\u672f\u7279\u6027\uff1a<br \/>\n\u2713 \u58c1\u539a \u2013 0.01\u6beb\u7c73<br \/>\n\u2713 \u6574\u4f53\u957f\u5ea6\u7ea680\u6beb\u7c73<br \/>\n\u2713 \u7531\u900f\u660e\u3001\u65b0\u9c9c\u3001\u5f7b\u5e95\u6e05\u6d01\u7684\u73bb\u7483\u62c9\u5236\u800c\u6210<br \/>\n\u2713 \u4e00\u7aef\u5448<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%bc%8f%e6%96%97\/\" title=\"View all posts in \u6f0f\u6597\" target=\"_blank\">\u6f0f\u6597<\/a>\u72b6\uff0c\u53e6\u4e00\u7aef<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%86%e5%b0%81\/\" title=\"View all posts in \u5bc6\u5c01\" target=\"_blank\">\u5bc6\u5c01<\/a><br \/>\n\u2713 \u91c7\u7528\u6613\u8fa8\u8bc6\u7684\u5f69\u8272\u7f16\u7801\u73bb\u7483\u5305\u88c5\uff0c\u6bcf\u76d2\u7ea625\u652f<br \/>\n\u2713 \u5355\u652f\u73bb\u7483\u7ba1\u53ef\u8f7b\u677e\u4ece\u5305\u88c5\u4e2d\u53d6\u51fa\uff0c\u65e0\u9700\u5728<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%ae%b9%e5%99%a8\/\" title=\"View all posts in \u5bb9\u5668\" target=\"_blank\">\u5bb9\u5668<\/a>\u4e2d\u7ffb\u627e<\/p>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles\/tag\/01-qz-0-1-mm\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 8pt;\" aria-label=\"01-QZ-0.1 mm (21\u4e2a\u9879\u76ee)\">01-QZ-0.1 mm<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/05-qz-0-5-mm\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 8pt;\" aria-label=\"05-QZ-0.5 mm (21\u4e2a\u9879\u76ee)\">05-QZ-0.5 mm<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles-supper\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 22pt;\" aria-label=\"Charles Supper (70\u4e2a\u9879\u76ee)\">Charles Supper<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 17.058823529412pt;\" aria-label=\"Charles\u6bdb\u7ec6\u7ba1 (46\u4e2a\u9879\u76ee)\">Charles\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-4 tag-link-position-5\" style=\"font-size: 12.941176470588pt;\" aria-label=\"Charles\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (32\u4e2a\u9879\u76ee)\">Charles\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-5 tag-link-position-6\" style=\"font-size: 17.607843137255pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (48\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-6 tag-link-position-7\" style=\"font-size: 10.470588235294pt;\" aria-label=\"\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (26\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm \u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 \u7528\u4e8eX\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\u2014\u2014\u77f3\u82f1\uff08QZ\uff09 Charles Supper\u516c\u53f8\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50 <\/p>\n","protected":false},"author":25,"featured_media":533,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[1],"tags":[167,165,126,155,156,154,152],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles\/\u7f8e\u56fd\u539f\u88c5-charles-supper-15-qz-1-5-mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u73b0\u8d27\u4f9b\u5e94\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934\" \/>\n<meta property=\"og:description\" content=\"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm \u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 \u7528\u4e8eX\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\u2014\u2014\u77f3\u82f1\uff08QZ\uff09 Charles Supper\u516c\u53f8\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles\/\u7f8e\u56fd\u539f\u88c5-charles-supper-15-qz-1-5-mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u73b0\u8d27\u4f9b\u5e94\/\" \/>\n<meta property=\"og:site_name\" content=\"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T08:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\u5c4f\u5e55\u622a\u56fe-2025-12-25-153014-1-e1766656287263.png\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"222\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u8054\u7cfb\u4eba\uff1a\u5510\u7ecf\u7406 15821984229\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles\/\",\"name\":\"charles \\u5fae\\u5b9a\\u4f4d\\u5668 \\u6d4b\\u89d2\\u4eea\\u5934 \\u7eba\\u9524\\u53f0 \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u6676\\u4f53\\u751f\\u957f\\u5ba4 \\u5bc6\\u5c01\\u4ea7\\u54c1 \\u6bdb\\u7ec6\\u7ba1\\u5bc6\\u5c01\\u8721 \\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668 \\u77f3\\u58a8\\u5355\\u8272\\u5668 \\u6a21\\u578b\\u5f2f\\u66f2\\u673a \\u6d4b\\u89d2\\u4eea\\u5934\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\\u5c4f\\u5e55\\u622a\\u56fe-2025-12-25-153014-1-e1766656287263.png\",\"contentUrl\":\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\\u5c4f\\u5e55\\u622a\\u56fe-2025-12-25-153014-1-e1766656287263.png\",\"width\":273,\"height\":222},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/\",\"name\":\"\\u7f8e\\u56fd\\u539f\\u88c5 Charles Supper 15-QZ-1.5 mm\\u77f3\\u82f1\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u73b0\\u8d27\\u4f9b\\u5e94 - charles \\u5fae\\u5b9a\\u4f4d\\u5668 \\u6d4b\\u89d2\\u4eea\\u5934 \\u7eba\\u9524\\u53f0 \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u6676\\u4f53\\u751f\\u957f\\u5ba4 \\u5bc6\\u5c01\\u4ea7\\u54c1 \\u6bdb\\u7ec6\\u7ba1\\u5bc6\\u5c01\\u8721 \\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668 \\u77f3\\u58a8\\u5355\\u8272\\u5668 \\u6a21\\u578b\\u5f2f\\u66f2\\u673a \\u6d4b\\u89d2\\u4eea\\u5934\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#primaryimage\"},\"datePublished\":\"2026-05-13T08:31:34+00:00\",\"dateModified\":\"2026-05-13T08:31:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/c0ed2b617a5db237548be9c5bbc14cfc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fd\\u539f\\u88c5 Charles Supper 15-QZ-1.5 mm\\u77f3\\u82f1\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u73b0\\u8d27\\u4f9b\\u5e94\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/c0ed2b617a5db237548be9c5bbc14cfc\",\"name\":\"\\u8054\\u7cfb\\u4eba\\uff1a\\u5510\\u7ecf\\u7406 15821984229\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#personlogo\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0cd6c6f78e3687a6587da44a6fb2022b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0cd6c6f78e3687a6587da44a6fb2022b?s=96&d=mm&r=g\",\"caption\":\"\\u8054\\u7cfb\\u4eba\\uff1a\\u5510\\u7ecf\\u7406 15821984229\"},\"sameAs\":[\"http:\/\/www.bihec.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles\/\u7f8e\u56fd\u539f\u88c5-charles-supper-15-qz-1-5-mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u73b0\u8d27\u4f9b\u5e94\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","og_description":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm \u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 \u7528\u4e8eX\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\u2014\u2014\u77f3\u82f1\uff08QZ\uff09 Charles Supper\u516c\u53f8\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50","og_url":"https:\/\/www.bihec.com\/charles\/\u7f8e\u56fd\u539f\u88c5-charles-supper-15-qz-1-5-mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u73b0\u8d27\u4f9b\u5e94\/","og_site_name":"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","article_published_time":"2026-05-13T08:31:34+00:00","og_image":[{"width":273,"height":222,"url":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\u5c4f\u5e55\u622a\u56fe-2025-12-25-153014-1-e1766656287263.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u8054\u7cfb\u4eba\uff1a\u5510\u7ecf\u7406 15821984229"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles\/#website","url":"https:\/\/www.bihec.com\/charles\/","name":"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\u5c4f\u5e55\u622a\u56fe-2025-12-25-153014-1-e1766656287263.png","contentUrl":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2025\/12\/\u5c4f\u5e55\u622a\u56fe-2025-12-25-153014-1-e1766656287263.png","width":273,"height":222},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#webpage","url":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/","name":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94 - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#primaryimage"},"datePublished":"2026-05-13T08:31:34+00:00","dateModified":"2026-05-13T08:31:34+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/c0ed2b617a5db237548be9c5bbc14cfc"},"breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles\/%e7%be%8e%e5%9b%bd%e5%8e%9f%e8%a3%85-charles-supper-15-qz-1-5-mm%e7%9f%b3%e8%8b%b1%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%8e%b0%e8%b4%a7%e4%be%9b%e5%ba%94\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fd\u539f\u88c5 Charles Supper 15-QZ-1.5 mm\u77f3\u82f1\u8584\u58c1\u6bdb\u7ec6\u7ba1 \u73b0\u8d27\u4f9b\u5e94"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/c0ed2b617a5db237548be9c5bbc14cfc","name":"\u8054\u7cfb\u4eba\uff1a\u5510\u7ecf\u7406 15821984229","image":{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles\/#personlogo","inLanguage":"zh-CN","url":"https:\/\/secure.gravatar.com\/avatar\/0cd6c6f78e3687a6587da44a6fb2022b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cd6c6f78e3687a6587da44a6fb2022b?s=96&d=mm&r=g","caption":"\u8054\u7cfb\u4eba\uff1a\u5510\u7ecf\u7406 15821984229"},"sameAs":["http:\/\/www.bihec.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/583"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/comments?post=583"}],"version-history":[{"count":1,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/583\/revisions"}],"predecessor-version":[{"id":584,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/583\/revisions\/584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/media\/533"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/media?parent=583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/categories?post=583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/tags?post=583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}