﻿{"id":503,"date":"2025-05-30T15:24:40","date_gmt":"2025-05-30T07:24:40","guid":{"rendered":"https:\/\/www.bihec.com\/charles\/?p=503"},"modified":"2025-05-30T15:24:40","modified_gmt":"2025-05-30T07:24:40","slug":"charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/","title":{"rendered":"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ)"},"content":{"rendered":"<p><a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles-supper\/\" title=\"View all posts in Charles Supper\" target=\"_blank\">Charles Supper<\/a><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\uff0c<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u77f3\u82f1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\uff0c40mm\u957f\uff0c\u65e0<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%bc%8f%e6%96%97\/\" title=\"View all posts in \u6f0f\u6597\" target=\"_blank\">\u6f0f\u6597<\/a> \u2013 <a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1\/\" title=\"View all posts in \u77f3\u82f1\" target=\"_blank\">\u77f3\u82f1<\/a> (40<a href=\"https:\/\/www.bihec.com\/charles\/tag\/qz\/\" title=\"View all posts in QZ\" target=\"_blank\">QZ<\/a>)<\/p>\n<p><strong><a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles\/\" title=\"View all posts in Charles\" target=\"_blank\">Charles<\/a> Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u7684<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e8%96%84%e5%a3%81\/\" title=\"View all posts in \u8584\u58c1\" target=\"_blank\">\u8584\u58c1<\/a><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u6bdb\u7ec6\u7ba1<\/a>\u53ef\u4f9b\u9009\u62e9\u3002\u77f3\u82f1\u6bdb\u7ec6\u7ba1\u662f 40 \u6beb\u7c73\u957f\u7684\u76f4\u7ba1\u3002\u5b83\u4eec\u5728\u6bdb\u7ec6\u7ba1\u7684\u9876\u90e8\u662f\u5f00\u653e\u7684\uff0c\u5728\u6bdb\u7ec6\u7ba1\u7684\u5e95\u90e8\u662f\u5c01\u95ed\u7684\uff0c\u5e76\u4e14\u6ca1\u6709\u6f0f\u6597\u3002\u6bcf\u4e2a\u5305\u88c5 25 \u6839\u7ba1\u5b50<\/strong><br \/>\n\u63d0\u4f9b 1.0mm\u30012.0mm \u548c ***4.0mm \u7684\u5916\u5f84\u3002*** 5 \u4ef6\u5957<\/p>\n<p><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%89%b9%e6%ae%8a%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u7279\u6b8a\u73bb\u7483\" target=\"_blank\">\u7279\u6b8a\u73bb\u7483<\/a>\u00a0(<a href=\"https:\/\/www.bihec.com\/charles\/tag\/sg\/\" title=\"View all posts in SG\" target=\"_blank\">SG<\/a>) \u2013 <a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%8c%e7%a1%bc-bg\/\" title=\"View all posts in \u5bcc\u787c (BG)\" target=\"_blank\">\u5bcc\u787c (BG)<\/a> \u2013\u00a0\u77f3\u82f1\u00a0(QZ) \u2013 \u65e0\u6f0f\u6597\u5f00\u53e3 (SQZ) \u2013 \u5e26\u6f0f\u6597\u5f00\u53e3 (OQZ)<br \/>\n\u6309\u7167Charles Supper\u516c\u53f8\u7684\u6700\u9ad8\u6807\u51c6\u5236\u9020\u3002<\/p>\n<p>\u6807\u51c6\u73bb\u7483\u6280\u672f\u7279\u70b9\uff1a<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-752615 alignright\" src=\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/04\/img_62660d0ca6181.png\" alt=\"\" width=\"295\" height=\"205\" \/><\/p>\n<ul>\n<li>\u58c1\u539a \u2013 0.01mm<\/li>\n<li>\u5927\u7ea6\u603b\u957f\u5ea6 40mm<\/li>\n<li>\u7531\u5e72\u51c0\u3001\u65b0\u9c9c\u3001\u9002\u5f53\u6e05\u6d01\u7684\u73bb\u7483\u5236\u6210<\/li>\n<li>\u76f4\u7ba1\u4e0a\u5f00\u4e0b\u95ed<\/li>\n<li>\u4ee5\u5305\u542b 25 \u7ba1\u6216 5 \u7ba1\u7684\u975e\u6df7\u6dc6\u8272\u6807\u73bb\u7483\u5305\u88c5\u63d0\u4f9b<\/li>\n<li>\u5355\u4e2a\u7ba1\u5b50\u5f88\u5bb9\u6613\u4ece\u73bb\u7483\u5305\u88c5\u4e2d\u53d6\u51fa\uff0c\u65e0\u9700\u6478\u7d22\u548c\u641c\u7d22<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%ae%b9%e5%99%a8\/\" title=\"View all posts in \u5bb9\u5668\" target=\"_blank\">\u5bb9\u5668<\/a><\/li>\n<li><strong>\u81ea 1972 \u5e74\u4ee5\u6765\u72ec\u5bb6\u53d1\u884c<\/strong><\/li>\n<li><strong>\u6211\u4eec\u7684\u5e93\u5b58\u4e2d\u6709 50 \u591a\u79cd\u5c3a\u5bf8\u53ef\u4f9b\u9009\u62e9\uff0c\u53ef\u7acb\u5373\u53d1\u8d27\u3002<\/strong><\/li>\n<li><strong>\u53ef\u4ee5\u5236\u9020\u7279\u6b8a\u8ba2\u5355\u7684\u6bdb\u7ec6\u7ba1\uff0c\u5e76\u5c06\u6839\u636e\u60a8\u7684\u8981\u6c42\u548c\u63d0\u4f9b\u7684\u89c4\u683c\u8fdb\u884c\u62a5\u4ef7\u3002<\/strong><\/li>\n<\/ul>\n<hr \/>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td><strong>\u6211\u4eec\u7684\u6bdb\u7ec6\u7ba1\u7684\u7ebf\u6027\u5438\u6536\u7cfb\u6570<\/strong><br \/>\n&nbsp;<\/p>\n<table border=\"0\" width=\"90%\" cellspacing=\"3\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td class=\"tbcapillary\" width=\"30%\"><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%89%b9%e7%a7%8d%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u7279\u79cd\u73bb\u7483\" target=\"_blank\">\u7279\u79cd\u73bb\u7483<\/a><\/strong><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong><a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%8c%e7%a1%bc\/\" title=\"View all posts in \u5bcc\u787c\" target=\"_blank\">\u5bcc\u787c<\/a><\/strong><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong>\u77f3\u82f1<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">*\u5e93\u5361\u8f90\u5c04<\/td>\n<td class=\"tdcapillary\">110.8<\/td>\n<td class=\"tdcapillary\">71.0<\/td>\n<td class=\"tdcapillary\">75.8<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">*\u83ab\u5361\u8f90\u5c04<\/td>\n<td class=\"tdcapillary\">11.95<\/td>\n<td class=\"tdcapillary\">7.35<\/td>\n<td class=\"tdcapillary\">8.20<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">\u8f6f\u5316\u6e29\u5ea6<\/td>\n<td class=\"tdcapillary\">715\u00baC<\/td>\n<td class=\"tdcapillary\">820\u00baC<\/td>\n<td class=\"tdcapillary\">1730\u00baC<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\"><\/td>\n<td class=\"tdcapillary\">1319\u00baF<\/td>\n<td class=\"tdcapillary\">1508\u00baF<\/td>\n<td class=\"tdcapillary\">3145\u00baF<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles-supper\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 22pt;\" aria-label=\"Charles Supper (63\u4e2a\u9879\u76ee)\">Charles Supper<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 18.181818181818pt;\" aria-label=\"Charles\u6bdb\u7ec6\u7ba1 (39\u4e2a\u9879\u76ee)\">Charles\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/charles%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 15.636363636364pt;\" aria-label=\"Charles\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (28\u4e2a\u9879\u76ee)\">Charles\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e5%af%8c%e7%a1%bc%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 15.090909090909pt;\" aria-label=\"\u5bcc\u787c\u8584\u58c1\u6bdb\u7ec6\u7ba1 (26\u4e2a\u9879\u76ee)\">\u5bcc\u787c\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-4 tag-link-position-5\" style=\"font-size: 18.545454545455pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (41\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%89%b9%e6%ae%8a%e7%8e%bb%e7%92%83%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-5 tag-link-position-6\" style=\"font-size: 10.909090909091pt;\" aria-label=\"\u7279\u6b8a\u73bb\u7483\u8584\u58c1\u6bdb\u7ec6\u7ba1 (15\u4e2a\u9879\u76ee)\">\u7279\u6b8a\u73bb\u7483\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-6 tag-link-position-7\" style=\"font-size: 13.818181818182pt;\" aria-label=\"\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (22\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%ae%a1%e5%be%84%e4%b8%ba-0-1mm-od-5-0mm-od\/\" class=\"tag-cloud-link tag-link-7 tag-link-position-8\" style=\"font-size: 8pt;\" aria-label=\"\u7ba1\u5f84\u4e3a 0.1mm OD\u2013 5.0mm OD (10\u4e2a\u9879\u76ee)\">\u7ba1\u5f84\u4e3a 0.1mm OD\u2013 5.0mm OD<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e7%be%8e%e5%9b%bdcharles\/\" class=\"tag-cloud-link tag-link-8 tag-link-position-9\" style=\"font-size: 19.272727272727pt;\" aria-label=\"\u7f8e\u56fdCharles (45\u4e2a\u9879\u76ee)\">\u7f8e\u56fdCharles<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-9 tag-link-position-10\" style=\"font-size: 18.727272727273pt;\" aria-label=\"\u8584\u58c1\u6bdb\u7ec6\u7ba1 (42\u4e2a\u9879\u76ee)\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) Charles Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\u53ef\u4f9b\u9009\u62e9\u3002\u77f3\u82f1\u6bdb\u7ec6\u7ba1\u662f 40  <\/p>\n","protected":false},"author":33,"featured_media":394,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[4],"tags":[126,155,156,136,154,138,152,9,5,6],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934<\/title>\n<meta name=\"description\" content=\"\u4ea7\u54c1\u54a8\u8be2 \u9f9a\u7ecf\u7406 18721868497 \u5fae\u4fe1\u540c\u53f7\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles\/charles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934\" \/>\n<meta property=\"og:description\" content=\"\u4ea7\u54c1\u54a8\u8be2 \u9f9a\u7ecf\u7406 18721868497 \u5fae\u4fe1\u540c\u53f7\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles\/charles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1\/\" \/>\n<meta property=\"og:site_name\" content=\"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T07:24:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\u5fae\u4fe1\u622a\u56fe_20241219171530.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"492\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9f9a\u7ecf\u7406 18721868497\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles\/\",\"name\":\"charles \\u5fae\\u5b9a\\u4f4d\\u5668 \\u6d4b\\u89d2\\u4eea\\u5934 \\u7eba\\u9524\\u53f0 \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u6676\\u4f53\\u751f\\u957f\\u5ba4 \\u5bc6\\u5c01\\u4ea7\\u54c1 \\u6bdb\\u7ec6\\u7ba1\\u5bc6\\u5c01\\u8721 \\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668 \\u77f3\\u58a8\\u5355\\u8272\\u5668 \\u6a21\\u578b\\u5f2f\\u66f2\\u673a \\u6d4b\\u89d2\\u4eea\\u5934\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\\u5fae\\u4fe1\\u622a\\u56fe_20241219171530.jpg\",\"contentUrl\":\"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\\u5fae\\u4fe1\\u622a\\u56fe_20241219171530.jpg\",\"width\":492,\"height\":370},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/\",\"name\":\"Charles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u77f3\\u82f1\\u6bdb\\u7ec6\\u7ba1\\uff0c40mm\\u957f\\uff0c\\u65e0\\u6f0f\\u6597 \\u2013 \\u77f3\\u82f1 (40QZ) - charles \\u5fae\\u5b9a\\u4f4d\\u5668 \\u6d4b\\u89d2\\u4eea\\u5934 \\u7eba\\u9524\\u53f0 \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 \\u6676\\u4f53\\u751f\\u957f\\u5ba4 \\u5bc6\\u5c01\\u4ea7\\u54c1 \\u6bdb\\u7ec6\\u7ba1\\u5bc6\\u5c01\\u8721 \\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668 \\u77f3\\u58a8\\u5355\\u8272\\u5668 \\u6a21\\u578b\\u5f2f\\u66f2\\u673a \\u6d4b\\u89d2\\u4eea\\u5934\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#primaryimage\"},\"datePublished\":\"2025-05-30T07:24:40+00:00\",\"dateModified\":\"2025-05-30T07:24:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/298282adf2735ffc0d42acb827e3bd3b\"},\"description\":\"\\u4ea7\\u54c1\\u54a8\\u8be2 \\u9f9a\\u7ecf\\u7406 18721868497 \\u5fae\\u4fe1\\u540c\\u53f7\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u77f3\\u82f1\\u6bdb\\u7ec6\\u7ba1\\uff0c40mm\\u957f\\uff0c\\u65e0\\u6f0f\\u6597 \\u2013 \\u77f3\\u82f1 (40QZ)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/298282adf2735ffc0d42acb827e3bd3b\",\"name\":\"\\u9f9a\\u7ecf\\u7406 18721868497\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles\/#personlogo\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cd8b608325555e2bd2c184d144e1f022?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cd8b608325555e2bd2c184d144e1f022?s=96&d=mm&r=g\",\"caption\":\"\\u9f9a\\u7ecf\\u7406 18721868497\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","description":"\u4ea7\u54c1\u54a8\u8be2 \u9f9a\u7ecf\u7406 18721868497 \u5fae\u4fe1\u540c\u53f7","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles\/charles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1\/","og_locale":"zh_CN","og_type":"article","og_title":"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","og_description":"\u4ea7\u54c1\u54a8\u8be2 \u9f9a\u7ecf\u7406 18721868497 \u5fae\u4fe1\u540c\u53f7","og_url":"https:\/\/www.bihec.com\/charles\/charles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1\/","og_site_name":"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","article_published_time":"2025-05-30T07:24:40+00:00","og_image":[{"width":492,"height":370,"url":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\u5fae\u4fe1\u622a\u56fe_20241219171530.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9f9a\u7ecf\u7406 18721868497"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles\/#website","url":"https:\/\/www.bihec.com\/charles\/","name":"charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\u5fae\u4fe1\u622a\u56fe_20241219171530.jpg","contentUrl":"https:\/\/www.bihec.com\/charles\/wp-content\/uploads\/sites\/1446\/2024\/12\/\u5fae\u4fe1\u622a\u56fe_20241219171530.jpg","width":492,"height":370},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#webpage","url":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/","name":"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ) - charles \u5fae\u5b9a\u4f4d\u5668 \u6d4b\u89d2\u4eea\u5934 \u7eba\u9524\u53f0 \u8584\u58c1\u6bdb\u7ec6\u7ba1 \u6676\u4f53\u751f\u957f\u5ba4 \u5bc6\u5c01\u4ea7\u54c1 \u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u8721 \u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 \u77f3\u58a8\u5355\u8272\u5668 \u6a21\u578b\u5f2f\u66f2\u673a \u6d4b\u89d2\u4eea\u5934","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#primaryimage"},"datePublished":"2025-05-30T07:24:40+00:00","dateModified":"2025-05-30T07:24:40+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/298282adf2735ffc0d42acb827e3bd3b"},"description":"\u4ea7\u54c1\u54a8\u8be2 \u9f9a\u7ecf\u7406 18721868497 \u5fae\u4fe1\u540c\u53f7","breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles\/charles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c40mm%e9%95%bf%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles\/"},{"@type":"ListItem","position":2,"name":"Charles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0c40mm\u957f\uff0c\u65e0\u6f0f\u6597 \u2013 \u77f3\u82f1 (40QZ)"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles\/#\/schema\/person\/298282adf2735ffc0d42acb827e3bd3b","name":"\u9f9a\u7ecf\u7406 18721868497","image":{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles\/#personlogo","inLanguage":"zh-CN","url":"https:\/\/secure.gravatar.com\/avatar\/cd8b608325555e2bd2c184d144e1f022?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd8b608325555e2bd2c184d144e1f022?s=96&d=mm&r=g","caption":"\u9f9a\u7ecf\u7406 18721868497"}}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/503"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/comments?post=503"}],"version-history":[{"count":1,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/503\/revisions"}],"predecessor-version":[{"id":516,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/posts\/503\/revisions\/516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/media\/394"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/media?parent=503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/categories?post=503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles\/wp-json\/wp\/v2\/tags?post=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}