﻿{"id":752879,"date":"2025-05-09T19:16:46","date_gmt":"2025-05-09T11:16:46","guid":{"rendered":"https:\/\/www.bihec.com\/charles-supper\/?p=752879"},"modified":"2025-05-09T19:16:46","modified_gmt":"2025-05-09T11:16:46","slug":"%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/","title":{"rendered":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 &#8211; \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ &#8211; 2.5mm *"},"content":{"rendered":"<p><strong>Charles Supper Company<\/strong>\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50\u5168\u7684<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\uff0c\u5e93\u5b58\u5c3a\u5bf8\u4ece0.1mm\u5916\u5f84\u81f35.0mm\u5916\u5f84\uff0c\u6750\u8d28\u5305\u62ec<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%89%b9%e7%a7%8d%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u7279\u79cd\u73bb\u7483\" target=\"_blank\">\u7279\u79cd\u73bb\u7483<\/a>\u3001<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%af%8c%e7%a1%bc%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u5bcc\u787c\u73bb\u7483\" target=\"_blank\">\u5bcc\u787c\u73bb\u7483<\/a>\u548c<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1\/\" title=\"View all posts in \u77f3\u82f1\" target=\"_blank\">\u77f3\u82f1<\/a>\u3002\u53ef\u7acb\u5373\u4ea4\u8d27\u3002<\/p>\n<p>\u7279\u79cd<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u73bb\u7483\" target=\"_blank\">\u73bb\u7483<\/a>\uff08SG\uff09\u25c6 \u5bcc\u787c\u73bb\u7483\uff08BG\uff09\u25c6 \u77f3\u82f1\uff08QZ\uff09\u29bf \u7279\u79cd\u77f3\u82f1\uff08SQZ\uff09\u25c6 \u5149\u5b66\u77f3\u82f1\uff08OQZ\uff09\u25c6 40\u7cfb\u5217\u7279\u79cd\u77f3\u82f1\uff0840SQZ\uff09\u25c6 40\u7cfb\u5217\u5149\u5b66\u77f3\u82f1\uff0840OQZ\uff09\u25c6<br \/>\n\u6240\u6709\u4ea7\u54c1\u5747\u6309\u7167\u67e5\u5c14\u65af\u00b7\u8428\u73c0\u516c\u53f8\u6700\u9ad8\u6807\u51c6\u5236\u9020\u3002<\/p>\n<p>\u6807\u51c6\u73bb\u7483\u6280\u672f\u7279\u70b9\uff1a<br \/>\n\u2713 \u58c1\u539a\uff1a0.01mm<br \/>\n\u2713 \u603b\u957f\u5ea6\u7ea680mm<br \/>\n\u2713 \u91c7\u7528\u900f\u660e\u3001\u65b0\u9c9c\u4e14\u5f7b\u5e95\u6e05\u6d01\u7684\u73bb\u7483\u62c9\u5236<br \/>\n\u2713 \u4e00\u7aef\u4e3a\u6f0f\u6597\u5f62\uff0c\u53e6\u4e00\u7aef\u5c01\u95ed<br \/>\n\u2713 \u91c7\u7528\u989c\u8272\u7f16\u7801\u7684\u73bb\u7483\u5305\u88c5\uff0c\u907f\u514d\u6df7\u6dc6\uff0c\u6bcf\u5305\u542b25\u652f<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u6bdb\u7ec6\u7ba1<\/a><br \/>\n\u2713 \u6bcf\u652f\u6bdb\u7ec6\u7ba1\u53ef\u8f7b\u677e\u53d6\u51fa\uff0c\u65e0\u9700\u5728\u5bb9\u5668\u4e2d\u7ffb\u627e<\/p>\n<p>\u2606 \u81ea1972\u5e74\u4ee5\u6765\u4e13\u5c5e\u5236\u9020<br \/>\n\u2606 \u5e93\u5b58\u4e2d\u6709\u8d85\u8fc760\u79cd\u89c4\u683c\uff0c\u53ef\u7acb\u5373\u53d1\u8d27<br \/>\n\u2606 \u53ef\u6309\u9700\u5b9a\u5236\u7279\u6b8a\u89c4\u683c\u6bdb\u7ec6\u7ba1\uff0c\u6b22\u8fce\u63d0\u4f9b\u53c2\u6570\u4ee5\u83b7\u53d6\u62a5\u4ef7\u548c\u751f\u4ea7\u5b89\u6392<\/p>\n<p>\u6211\u4eec\u6bdb\u7ec6\u7ba1\u7684\u7ebf\u6027\u5438\u6536\u7cfb\u6570\u5982\u4e0b\uff1a<\/p>\n<table>\n<thead>\n<tr>\n<th>\u8f90\u5c04\u7c7b\u578b\/\u53c2\u6570<\/th>\n<th>\u7279\u79cd\u73bb\u7483\uff08Special Glass\uff09<\/th>\n<th>\u5bcc\u787c\u73bb\u7483\uff08Boron-Rich\uff09<\/th>\n<th>\u77f3\u82f1\uff08Quartz\uff09<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>*CuKa \u8f90\u5c04\u5438\u6536\u7cfb\u6570<\/td>\n<td>110.8<\/td>\n<td>71.0<\/td>\n<td>75.8<\/td>\n<\/tr>\n<tr>\n<td>*MoKa \u8f90\u5c04\u5438\u6536\u7cfb\u6570<\/td>\n<td>11.95<\/td>\n<td>7.35<\/td>\n<td>8.20<\/td>\n<\/tr>\n<tr>\n<td>\u8f6f\u5316\u6e29\u5ea6\uff08\u2103\uff09<\/td>\n<td>715\u2103<\/td>\n<td>820\u2103<\/td>\n<td>1730\u2103<\/td>\n<\/tr>\n<tr>\n<td>\u8f6f\u5316\u6e29\u5ea6\uff08\u2109\uff09<\/td>\n<td>1319\u2109<\/td>\n<td>1508\u2109<\/td>\n<td>3145\u2109<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u8fd9\u4e9b\u53c2\u6570\u53ef\u5e2e\u52a9\u60a8\u9009\u62e9\u9002\u5408\u7279\u5b9a\u8f90\u5c04\u6e90\u548c\u9ad8\u6e29\u73af\u5883\u4e0b\u4f7f\u7528\u7684\u6750\u6599\u3002\u9700\u8981\u6211\u5e2e\u60a8\u6839\u636e\u4f7f\u7528\u6761\u4ef6\u63a8\u8350\u4e00\u79cd\u6750\u6599\u5417\uff1f<\/p>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 10.742268041237pt;\" aria-label=\"X-Y\u5fae\u578b\u6ed1\u8f68 (19\u4e2a\u9879\u76ee)\">X-Y\u5fae\u578b\u6ed1\u8f68<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 22pt;\" aria-label=\"X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1 (118\u4e2a\u9879\u76ee)\">X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%af%8c%e7%a1%bc%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 16.659793814433pt;\" aria-label=\"\u5bcc\u787c\u6bdb\u7ec6\u7ba1 (50\u4e2a\u9879\u76ee)\">\u5bcc\u787c\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%af%8c%e7%a1%bc%e7%8e%bb%e7%92%83\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 15.649484536082pt;\" aria-label=\"\u5bcc\u787c\u73bb\u7483 (43\u4e2a\u9879\u76ee)\">\u5bcc\u787c\u73bb\u7483<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-4 tag-link-position-5\" style=\"font-size: 21.567010309278pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%89%b9%e6%ae%8a%e7%8e%bb%e7%92%83%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-5 tag-link-position-6\" style=\"font-size: 16.948453608247pt;\" aria-label=\"\u7279\u6b8a\u73bb\u7483\u6bdb\u7ec6\u7ba1 (53\u4e2a\u9879\u76ee)\">\u7279\u6b8a\u73bb\u7483\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%89%b9%e7%a7%8d%e7%8e%bb%e7%92%83\/\" class=\"tag-cloud-link tag-link-6 tag-link-position-7\" style=\"font-size: 15.79381443299pt;\" aria-label=\"\u7279\u79cd\u73bb\u7483 (44\u4e2a\u9879\u76ee)\">\u7279\u79cd\u73bb\u7483<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%8e%bb%e7%92%83\/\" class=\"tag-cloud-link tag-link-7 tag-link-position-8\" style=\"font-size: 15.79381443299pt;\" aria-label=\"\u73bb\u7483 (44\u4e2a\u9879\u76ee)\">\u73bb\u7483<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1\/\" class=\"tag-cloud-link tag-link-8 tag-link-position-9\" style=\"font-size: 15.649484536082pt;\" aria-label=\"\u77f3\u82f1 (43\u4e2a\u9879\u76ee)\">\u77f3\u82f1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-9 tag-link-position-10\" style=\"font-size: 18.969072164948pt;\" aria-label=\"\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (73\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e7%8e%bb%e7%92%83\/\" class=\"tag-cloud-link tag-link-10 tag-link-position-11\" style=\"font-size: 13.051546391753pt;\" aria-label=\"\u77f3\u82f1\u73bb\u7483 (28\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u73bb\u7483<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa\/\" class=\"tag-cloud-link tag-link-11 tag-link-position-12\" style=\"font-size: 8pt;\" aria-label=\"\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea (12\u4e2a\u9879\u76ee)\">\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-12 tag-link-position-13\" style=\"font-size: 21.567010309278pt;\" aria-label=\"\u8584\u58c1\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Charles Supper Company\u63d0\u4f9b\u79cd\u7c7b\u6700\u9f50\u5168\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u5e93\u5b58\u5c3a\u5bf8\u4ece0.1mm\u5916\u5f84\u81f35.0mm\u5916\u5f84\uff0c\u6750\u8d28\u5305\u62ec\u7279\u79cd\u73bb\u7483\u3001\u5bcc\u787c\u73bb\u7483\u548c\u77f3\u82f1\u3002\u53ef\u7acb\u5373\u4ea4\u8d27\u3002 \u7279\u79cd\u73bb\u7483\uff08SG\uff09\u25c6 <\/p>\n","protected":false},"author":16,"featured_media":752846,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[97],"tags":[38,6,19,62,5,20,61,64,63,18,85,39,7],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"description\" content=\"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm *\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u7528\u4e8e-x-\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u77f3\u82f1-qz-\u6709\u5e93\u5b58-q-13\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:description\" content=\"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm *\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u7528\u4e8e-x-\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u77f3\u82f1-qz-\u6709\u5e93\u5b58-q-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-09T11:16:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"421\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png\",\"contentUrl\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png\",\"width\":421,\"height\":316},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/\",\"name\":\"\\u7f8e\\u56fdCharles Supper \\u7528\\u4e8e X \\u5c04\\u7ebf\\u884d\\u5c04\\u7684\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 - \\u77f3\\u82f1 (QZ) \\u6709\\u5e93\\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#primaryimage\"},\"datePublished\":\"2025-05-09T11:16:46+00:00\",\"dateModified\":\"2025-05-09T11:16:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\"},\"description\":\"\\u7f8e\\u56fdCharles Supper \\u7528\\u4e8e X \\u5c04\\u7ebf\\u884d\\u5c04\\u7684\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 - \\u77f3\\u82f1 (QZ) \\u6709\\u5e93\\u5b58 Quartz 25-QZ - 2.5mm *\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fdCharles Supper \\u7528\\u4e8e X \\u5c04\\u7ebf\\u884d\\u5c04\\u7684\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1 &#8211; \\u77f3\\u82f1 (QZ) \\u6709\\u5e93\\u5b58 Quartz 25-QZ &#8211; 2.5mm *\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\",\"name\":\"\\u9500\\u552e\\u7ecf\\u7406\\uff1a\\u6768\\u5a771015\\uff0817740862043\\u5fae\\u4fe1\\u540c\\u53f7\\uff09\",\"description\":\"\\u7535\\u8bdd\\uff1a400-840-1510\\u8f6c1005 \\u624b\\u673a\\uff1a177-40862043 \\u4f20\\u771f\\uff1a021-51062822 Email\\uff1a1015@bihec.com QQ:3319485260\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\u6bdb\u7ec6\u7ba1","description":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm *","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u7528\u4e8e-x-\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u77f3\u82f1-qz-\u6709\u5e93\u5b58-q-13\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\u6bdb\u7ec6\u7ba1","og_description":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm *","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u7528\u4e8e-x-\u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1-\u77f3\u82f1-qz-\u6709\u5e93\u5b58-q-13\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","article_published_time":"2025-05-09T11:16:46+00:00","og_image":[{"width":421,"height":316,"url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png","contentUrl":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2025\/05\/img_681ddd217fef9.png","width":421,"height":316},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/","name":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm * - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#primaryimage"},"datePublished":"2025-05-09T11:16:46+00:00","dateModified":"2025-05-09T11:16:46+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06"},"description":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 - \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ - 2.5mm *","breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e7%94%a8%e4%ba%8e-x-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e7%9a%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1-%e7%9f%b3%e8%8b%b1-qz-%e6%9c%89%e5%ba%93%e5%ad%98-q-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fdCharles Supper \u7528\u4e8e X \u5c04\u7ebf\u884d\u5c04\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 &#8211; \u77f3\u82f1 (QZ) \u6709\u5e93\u5b58 Quartz 25-QZ &#8211; 2.5mm *"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06","name":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","description":"\u7535\u8bdd\uff1a400-840-1510\u8f6c1005 \u624b\u673a\uff1a177-40862043 \u4f20\u771f\uff1a021-51062822 Email\uff1a1015@bihec.com QQ:3319485260"}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752879"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/comments?post=752879"}],"version-history":[{"count":1,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752879\/revisions"}],"predecessor-version":[{"id":752880,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752879\/revisions\/752880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media\/752846"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media?parent=752879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories?post=752879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/tags?post=752879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}