﻿{"id":752695,"date":"2022-05-01T21:47:19","date_gmt":"2022-05-01T13:47:19","guid":{"rendered":"https:\/\/www.bihec.com\/charles-supper\/?p=752695"},"modified":"2022-05-01T21:47:19","modified_gmt":"2022-05-01T13:47:19","slug":"%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/","title":{"rendered":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Charles Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u53ef\u4f9b\u9009\u62e9\u7684<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\uff0c\u6211\u4eec\u5907\u6709 0.1 mm\u5916\u5f84\u81f3 5.0 mm\u5916\u5f84\u7684\u5c3a\u5bf8\uff0c\u7531\u7279\u6b8a<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u73bb\u7483\" target=\"_blank\">\u73bb\u7483<\/a>\u3001\u5bcc\u787c\u548c<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1\/\" title=\"View all posts in \u77f3\u82f1\" target=\"_blank\">\u77f3\u82f1<\/a>\u5236\u6210\u3002\u73b0\u8d27\u3002<\/strong><\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"20\">\n<tbody>\n<tr>\n<td>\n<table border=\"0\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td><b>\u7279\u6b8a\u73bb\u7483 (SG)<\/b>\u00a0-\u5bcc\u787c (BG)\u00a0-\u77f3\u82f1 (QZ)\u00a0-\u5e26\u6f0f\u6597\u7684\u5f00\u53e3 (OQZ)\u00a0-\u65e0\u6f0f\u6597\u7684\u5f00\u53e3 (SQZ)<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong>\u6309\u7167Charles Supper \u516c\u53f8\u7684\u6700\u9ad8\u6807\u51c6\u5236\u9020\u3002<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong>\u6807\u51c6\u73bb\u7483\u6280\u672f\u7279\u70b9\uff1a<\/strong><\/li>\n<\/ul>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td>\n<ul>\n<li>\u58c1\u539a \u2013 0.01mm<\/li>\n<li>\u5927\u7ea6\u603b\u957f\u5ea6 80mm<\/li>\n<li>\u7531\u5e72\u51c0\u3001\u65b0\u9c9c\u3001\u9002\u5f53\u6e05\u6d01\u7684\u73bb\u7483\u5236\u6210<\/li>\n<li>\u4e00\u7aef\u4e3a\u6f0f\u6597\uff0c\u53e6\u4e00\u7aef\u5bc6\u5c01<\/li>\n<li>\u4ee5\u5305\u542b 25 \u4e2a\u8bd5\u7ba1\u7684\u975e\u6df7\u6dc6\u8272\u6807\u73bb\u7483\u5305\u88c5\u5f62\u5f0f\u63d0\u4f9b<\/li>\n<li>\u5355\u4e2a\u7ba1\u5b50\u5f88\u5bb9\u6613\u4ece\u73bb\u7483\u5305\u88c5\u4e2d\u53d6\u51fa\uff0c\u65e0\u9700\u6478\u7d22\u548c\u641c\u7d22\u5bb9\u5668<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong>\u81ea 1972 \u5e74\u4ee5\u6765\u72ec\u5bb6\u53d1\u884c<\/strong><\/li>\n<li><strong>\u6211\u4eec\u7684\u5e93\u5b58\u4e2d\u6709 50 \u591a\u79cd\u5c3a\u5bf8\u53ef\u4f9b\u9009\u62e9\uff0c\u53ef\u7acb\u5373\u53d1\u8d27\u3002<\/strong><\/li>\n<li><strong>\u53ef\u4ee5\u5236\u9020\u7279\u6b8a\u8ba2\u5355\u7684<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u6bdb\u7ec6\u7ba1<\/a>\uff0c\u5e76\u5c06\u6839\u636e\u60a8\u7684\u8981\u6c42\u548c\u63d0\u4f9b\u7684\u89c4\u683c\u8fdb\u884c\u62a5\u4ef7\u3002<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td>\u6bdb\u7ec6\u7ba1\u7684\u7ebf\u6027\u5438\u6536\u7cfb\u6570<br \/>\n<img decoding=\"async\" src=\"https:\/\/www.charles-supper.com\/images\/eq.png\" \/><\/p>\n<table border=\"0\" width=\"90%\" cellspacing=\"3\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td class=\"tbcapillary\" width=\"30%\"><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong>\u7279\u6b8a\u73bb\u7483<\/strong><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%af%8c%e7%a1%bc%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u5bcc\u787c\u73bb\u7483\" target=\"_blank\">\u5bcc\u787c\u73bb\u7483<\/a><\/strong><\/td>\n<td class=\"tbcapillary\" width=\"20%\"><strong><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u77f3\u82f1\u73bb\u7483\" target=\"_blank\">\u77f3\u82f1\u73bb\u7483<\/a><\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">*CuKa \u8f90\u5c04<\/td>\n<td class=\"tdcapillary\">110.8<\/td>\n<td class=\"tdcapillary\">71.0<\/td>\n<td class=\"tdcapillary\">75.8<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">*MoKa \u8f90\u5c04<\/td>\n<td class=\"tdcapillary\">11.95<\/td>\n<td class=\"tdcapillary\">7.35<\/td>\n<td class=\"tdcapillary\">8.20<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\">\u8f6f\u5316\u6e29\u5ea6<\/td>\n<td class=\"tdcapillary\">715\u00baC<\/td>\n<td class=\"tdcapillary\">820\u00baC<\/td>\n<td class=\"tdcapillary\">1730\u00baC<\/td>\n<\/tr>\n<tr>\n<td class=\"clcapillary\"><\/td>\n<td class=\"tdcapillary\">1319\u00baF<\/td>\n<td class=\"tdcapillary\">1508\u00baF<\/td>\n<td class=\"tdcapillary\">3145\u00baF<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 22pt;\" aria-label=\"X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1 (118\u4e2a\u9879\u76ee)\">X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 20pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 8pt;\" aria-label=\"\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (73\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 20pt;\" aria-label=\"\u8584\u58c1\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Charles Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u53ef\u4f9b\u9009\u62e9\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6211\u4eec\u5907\u6709 0.1 mm\u5916\u5f84\u81f3 5.0 mm\u5916\u5f84\u7684\u5c3a\u5bf8\uff0c\u7531\u7279\u6b8a\u73bb\u7483\u3001\u5bcc\u787c\u548c\u77f3\u82f1\u5236\u6210\u3002\u73b0\u8d27\u3002 <\/p>\n","protected":false},"author":16,"featured_media":752601,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[4],"tags":[6,5,18,7],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG) - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"description\" content=\"\u4e13\u4e1a\u4ee3\u7406\u8fdb\u53e3\u91c7\u8d2dCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\uff0c\u54a8\u8be2Charles Supper\u6bdb\u7ec6\u7ba1 \u4ef7\u683c\u4e0e\u552e\u540e\u53ef\u62e8\u6253\u70ed\u7ebf400-840-1510\u8054\u7cfb\u4e2d\u56fd\u4e0a\u6d77\u4ee3\u7406\u5546\uff0c\u83b7\u53d6\u66f4\u591aCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\u4fe1\u606f\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cx-\u5c04\u7ebf\u884d\u5c04\uff0c\u4e00-2\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG) - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:description\" content=\"\u4e13\u4e1a\u4ee3\u7406\u8fdb\u53e3\u91c7\u8d2dCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\uff0c\u54a8\u8be2Charles Supper\u6bdb\u7ec6\u7ba1 \u4ef7\u683c\u4e0e\u552e\u540e\u53ef\u62e8\u6253\u70ed\u7ebf400-840-1510\u8054\u7cfb\u4e2d\u56fd\u4e0a\u6d77\u4ee3\u7406\u5546\uff0c\u83b7\u53d6\u66f4\u591aCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\u4fe1\u606f\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cx-\u5c04\u7ebf\u884d\u5c04\uff0c\u4e00-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-01T13:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png\",\"contentUrl\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png\",\"width\":295,\"height\":205},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/\",\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u77f3\\u82f1\\u6bdb\\u7ec6\\u7ba1\\uff0cX \\u5c04\\u7ebf\\u884d\\u5c04\\uff0c\\u4e00\\u7aef\\u6f0f\\u6597\\uff0c\\u7279\\u6b8a\\u73bb\\u7483 (SG) - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#primaryimage\"},\"datePublished\":\"2022-05-01T13:47:19+00:00\",\"dateModified\":\"2022-05-01T13:47:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\"},\"description\":\"\\u4e13\\u4e1a\\u4ee3\\u7406\\u8fdb\\u53e3\\u91c7\\u8d2dCharles Supper\\u6bdb\\u7ec6\\u7ba1 \\u4ea7\\u54c1\\uff0c\\u54a8\\u8be2Charles Supper\\u6bdb\\u7ec6\\u7ba1 \\u4ef7\\u683c\\u4e0e\\u552e\\u540e\\u53ef\\u62e8\\u6253\\u70ed\\u7ebf400-840-1510\\u8054\\u7cfb\\u4e2d\\u56fd\\u4e0a\\u6d77\\u4ee3\\u7406\\u5546\\uff0c\\u83b7\\u53d6\\u66f4\\u591aCharles Supper\\u6bdb\\u7ec6\\u7ba1 \\u4ea7\\u54c1\\u4fe1\\u606f\\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u77f3\\u82f1\\u6bdb\\u7ec6\\u7ba1\\uff0cX \\u5c04\\u7ebf\\u884d\\u5c04\\uff0c\\u4e00\\u7aef\\u6f0f\\u6597\\uff0c\\u7279\\u6b8a\\u73bb\\u7483 (SG)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\",\"name\":\"\\u9500\\u552e\\u7ecf\\u7406\\uff1a\\u6768\\u5a771015\\uff0817740862043\\u5fae\\u4fe1\\u540c\\u53f7\\uff09\",\"description\":\"\\u7535\\u8bdd\\uff1a400-840-1510\\u8f6c1005 \\u624b\\u673a\\uff1a177-40862043 \\u4f20\\u771f\\uff1a021-51062822 Email\\uff1a1015@bihec.com QQ:3319485260\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG) - Charles Supper\u6bdb\u7ec6\u7ba1","description":"\u4e13\u4e1a\u4ee3\u7406\u8fdb\u53e3\u91c7\u8d2dCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\uff0c\u54a8\u8be2Charles Supper\u6bdb\u7ec6\u7ba1 \u4ef7\u683c\u4e0e\u552e\u540e\u53ef\u62e8\u6253\u70ed\u7ebf400-840-1510\u8054\u7cfb\u4e2d\u56fd\u4e0a\u6d77\u4ee3\u7406\u5546\uff0c\u83b7\u53d6\u66f4\u591aCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\u4fe1\u606f\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cx-\u5c04\u7ebf\u884d\u5c04\uff0c\u4e00-2\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG) - Charles Supper\u6bdb\u7ec6\u7ba1","og_description":"\u4e13\u4e1a\u4ee3\u7406\u8fdb\u53e3\u91c7\u8d2dCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\uff0c\u54a8\u8be2Charles Supper\u6bdb\u7ec6\u7ba1 \u4ef7\u683c\u4e0e\u552e\u540e\u53ef\u62e8\u6253\u70ed\u7ebf400-840-1510\u8054\u7cfb\u4e2d\u56fd\u4e0a\u6d77\u4ee3\u7406\u5546\uff0c\u83b7\u53d6\u66f4\u591aCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\u4fe1\u606f\u3002","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cx-\u5c04\u7ebf\u884d\u5c04\uff0c\u4e00-2\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","article_published_time":"2022-05-01T13:47:19+00:00","og_image":[{"width":295,"height":205,"url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png","contentUrl":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dff1bd6f600.png","width":295,"height":205},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/","name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG) - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#primaryimage"},"datePublished":"2022-05-01T13:47:19+00:00","dateModified":"2022-05-01T13:47:19+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06"},"description":"\u4e13\u4e1a\u4ee3\u7406\u8fdb\u53e3\u91c7\u8d2dCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\uff0c\u54a8\u8be2Charles Supper\u6bdb\u7ec6\u7ba1 \u4ef7\u683c\u4e0e\u552e\u540e\u53ef\u62e8\u6253\u70ed\u7ebf400-840-1510\u8054\u7cfb\u4e2d\u56fd\u4e0a\u6d77\u4ee3\u7406\u5546\uff0c\u83b7\u53d6\u66f4\u591aCharles Supper\u6bdb\u7ec6\u7ba1 \u4ea7\u54c1\u4fe1\u606f\u3002","breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8cx-%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%ef%bc%8c%e4%b8%80-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u77f3\u82f1\u6bdb\u7ec6\u7ba1\uff0cX \u5c04\u7ebf\u884d\u5c04\uff0c\u4e00\u7aef\u6f0f\u6597\uff0c\u7279\u6b8a\u73bb\u7483 (SG)"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06","name":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","description":"\u7535\u8bdd\uff1a400-840-1510\u8f6c1005 \u624b\u673a\uff1a177-40862043 \u4f20\u771f\uff1a021-51062822 Email\uff1a1015@bihec.com QQ:3319485260"}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752695"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/comments?post=752695"}],"version-history":[{"count":2,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752695\/revisions"}],"predecessor-version":[{"id":752697,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752695\/revisions\/752697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media\/752601"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media?parent=752695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories?post=752695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/tags?post=752695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}