﻿{"id":752606,"date":"2022-01-13T23:30:03","date_gmt":"2022-01-13T15:30:03","guid":{"rendered":"https:\/\/www.bihec.com\/charles-supper\/?p=752606"},"modified":"2022-01-13T23:30:03","modified_gmt":"2022-01-13T15:30:03","slug":"%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/","title":{"rendered":"\u7f8e\u56fdCharles Supper  \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 &#8211; \u77f3\u82f1 (SQZ)"},"content":{"rendered":"<p><strong>Charles Supper\u00a0 \u62e5\u6709\u79cd\u7c7b\u7e41\u591a\u7684<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u8584\u58c1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a><\/strong><\/p>\n<hr \/>\n<table border=\"0\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td><strong><span>Charles Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u7684\u8584\u58c1<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u6bdb\u7ec6\u7ba1<\/a>\u53ef\u4f9b\u9009\u62e9\u3002<\/span><\/p>\n<p><span>\u8fd9\u4e9b\u65b0\u7684\u5f00\u53e3<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" title=\"View all posts in \u77f3\u82f1\u6bdb\u7ec6\u7ba1\" target=\"_blank\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\u662f\u76f4\u7ba1\u3002\u5b83\u4eec\u5728\u6bdb\u7ec6\u7ba1\u7684\u4e24\u7aef\u90fd\u662f\u5f00\u653e\u7684\uff0c\u6ca1\u6709\u6f0f\u6597\u3002<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"20\">\n<tbody>\n<tr>\n<td>\n<table border=\"0\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td><a href=\"https:\/\/www.charles-supper.com\/en\/page\/product.cfm?idProduct=15\"><span>\u7279\u6b8a<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%8e%bb%e7%92%83\/\" title=\"View all posts in \u73bb\u7483\" target=\"_blank\">\u73bb\u7483<\/a> (SG)<\/span><\/a><span>\u00a0&#8211;<\/span><a href=\"https:\/\/www.charles-supper.com\/en\/page\/product.cfm?idProduct=16\"><span>\u5bcc\u787c (BG)<\/span><\/a><span>\u00a0&#8211;<\/span><a href=\"https:\/\/www.charles-supper.com\/en\/page\/product.cfm?idProduct=17\"><span><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1\/\" title=\"View all posts in \u77f3\u82f1\" target=\"_blank\">\u77f3\u82f1<\/a> (QZ)<\/span><\/a><span>\u00a0&#8211;<\/span><b><span>\u65e0\u6f0f\u6597\u5f00\u53e3 (SQZ)<\/span><\/b><span>\u00a0&#8211;<\/span><a href=\"https:\/\/www.charles-supper.com\/en\/page\/product.cfm?idProduct=41\"><span>\u5e26\u6f0f\u6597\u5f00\u53e3 (OQZ)<\/span><\/a><\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong><span>\u6309\u7167\u67e5\u5c14\u65af\u665a\u9910\u516c\u53f8\u7684\u6700\u9ad8\u6807\u51c6\u5236\u9020\u3002<\/span><\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong><span>\u6807\u51c6\u73bb\u7483\u6280\u672f\u7279\u70b9\uff1a<\/span><\/strong><\/li>\n<\/ul>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td>\n<ul>\n<li><span>\u58c1\u539a \u2013 0.01mm<\/span><\/li>\n<li><span>\u5927\u7ea6\u603b\u957f\u5ea6 80mm<\/span><\/li>\n<li><span>\u7531\u5e72\u51c0\u3001\u65b0\u9c9c\u3001\u9002\u5f53\u6e05\u6d01\u7684\u73bb\u7483\u5236\u6210<\/span><\/li>\n<li><span>\u4e24\u7aef\u5f00\u53e3\u7684\u76f4\u7ba1<\/span><\/li>\n<li><span>\u4ee5\u5305\u542b 25 \u4e2a\u8bd5\u7ba1\u7684\u975e\u6df7\u6dc6\u8272\u6807\u73bb\u7483\u5305\u88c5\u5f62\u5f0f\u63d0\u4f9b<\/span><\/li>\n<li><span>\u5355\u4e2a\u7ba1\u5b50\u5f88\u5bb9\u6613\u4ece\u73bb\u7483\u5305\u88c5\u4e2d\u53d6\u51fa\uff0c\u65e0\u9700\u6478\u7d22\u548c\u641c\u7d22\u5bb9\u5668<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li><strong><span>\u81ea 1972 \u5e74\u4ee5\u6765\u72ec\u5bb6\u53d1\u884c<\/span><\/strong><\/li>\n<li><strong><span>\u6211\u4eec\u7684\u5e93\u5b58\u4e2d\u6709 50 \u591a\u79cd\u5c3a\u5bf8\u53ef\u4f9b\u9009\u62e9\uff0c\u53ef\u7acb\u5373\u53d1\u8d27\u3002<\/span><\/strong><\/li>\n<li><strong><span>\u53ef\u4ee5\u5236\u9020\u7279\u6b8a\u8ba2\u5355\u7684\u6bdb\u7ec6\u7ba1\uff0c\u5e76\u5c06\u6839\u636e\u60a8\u7684\u8981\u6c42\u548c\u63d0\u4f9b\u7684\u89c4\u683c\u8fdb\u884c\u62a5\u4ef7\u3002<\/span><\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"qb-sougou-search\">\n<p>\u641c\u7d22<\/p>\n<p class=\"last-btn\">\u590d\u5236<\/p>\n<\/div>\n<p><audio controls=\"controls\"><\/audio><\/p>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 22pt;\" aria-label=\"X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1 (118\u4e2a\u9879\u76ee)\">X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%af%8c%e7%a1%bc%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 15.525pt;\" aria-label=\"\u5bcc\u787c\u6bdb\u7ec6\u7ba1 (50\u4e2a\u9879\u76ee)\">\u5bcc\u787c\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 21.475pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1%e5%ad%98%e5%82%a8%e5%ae%b9%e5%99%a8\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 10.625pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668 (26\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1%e5%af%86%e5%b0%81%e4%ba%a7%e5%93%81\/\" class=\"tag-cloud-link tag-link-4 tag-link-position-5\" style=\"font-size: 14.3pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u4ea7\u54c1 (43\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1\u5bc6\u5c01\u4ea7\u54c1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%89%b9%e6%ae%8a%e7%8e%bb%e7%92%83%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-5 tag-link-position-6\" style=\"font-size: 15.875pt;\" aria-label=\"\u7279\u6b8a\u73bb\u7483\u6bdb\u7ec6\u7ba1 (53\u4e2a\u9879\u76ee)\">\u7279\u6b8a\u73bb\u7483\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%9f%b3%e8%8b%b1%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-6 tag-link-position-7\" style=\"font-size: 18.325pt;\" aria-label=\"\u77f3\u82f1\u6bdb\u7ec6\u7ba1 (73\u4e2a\u9879\u76ee)\">\u77f3\u82f1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-7 tag-link-position-8\" style=\"font-size: 21.475pt;\" aria-label=\"\u8584\u58c1\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e9%bb%84%e9%93%9c%e8%af%95%e4%bb%b6%e5%ae%89%e8%a3%85%e9%94%80\/\" class=\"tag-cloud-link tag-link-8 tag-link-position-9\" style=\"font-size: 8pt;\" aria-label=\"\u9ec4\u94dc\u8bd5\u4ef6\u5b89\u88c5\u9500 (18\u4e2a\u9879\u76ee)\">\u9ec4\u94dc\u8bd5\u4ef6\u5b89\u88c5\u9500<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Charles Supper\u00a0 \u62e5\u6709\u79cd\u7c7b\u7e41\u591a\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1 Charles Supper \u516c\u53f8\u62e5\u6709\u6700\u591a\u7684\u8584\u58c1\u6bdb\u7ec6\u7ba1\u53ef\u4f9b\u9009\u62e9\u3002 \u8fd9\u4e9b\u65b0\u7684\u5f00\u53e3\u77f3\u82f1\u6bdb\u7ec6\u7ba1\u662f\u76f4\u7ba1\u3002\u5b83\u4eec\u5728\u6bdb\u7ec6\u7ba1\u7684\u4e24\u7aef\u90fd\u662f\u5f00\u653e <\/p>\n","protected":false},"author":16,"featured_media":752595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[3,15,4],"tags":[6,19,5,16,9,20,18,7,14],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 - \u77f3\u82f1 (SQZ) - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"description\" content=\"\u7f8e\u56fdCharles Supper\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8d85\u5927\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8fd9\u4e9b\u662f\u7a7a\u7684\u73bb\u7483\u5bb9\u5668\uff0c\u7528\u4e8e\u5bb9\u7eb3\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4ee5\u8fdb\u884c\u5b58\u50a8\u548c\u8fd0\u8f93\u3002\u6bcf\u4e2a\u5305\u88c52\u4e2a\u5bb9\u5668\u8d85\u5927\u578b\u5bb9\u5668\u5c06\u5bb9\u7eb3\u5916\u5f84\u4e3a3.0mm\u81f35.0mm\u7684\u6bdb\u7ec6\u7ba1\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1-sqz\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 - \u77f3\u82f1 (SQZ) - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:description\" content=\"\u7f8e\u56fdCharles Supper\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8d85\u5927\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8fd9\u4e9b\u662f\u7a7a\u7684\u73bb\u7483\u5bb9\u5668\uff0c\u7528\u4e8e\u5bb9\u7eb3\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4ee5\u8fdb\u884c\u5b58\u50a8\u548c\u8fd0\u8f93\u3002\u6bcf\u4e2a\u5305\u88c52\u4e2a\u5bb9\u5668\u8d85\u5927\u578b\u5bb9\u5668\u5c06\u5bb9\u7eb3\u5916\u5f84\u4e3a3.0mm\u81f35.0mm\u7684\u6bdb\u7ec6\u7ba1\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1-sqz\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-13T15:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png\",\"contentUrl\":\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png\",\"width\":295,\"height\":205},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/\",\"name\":\"\\u7f8e\\u56fdCharles Supper \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u4e24\\u7aef\\u5f00\\u53e3\\uff0c\\u65e0\\u6f0f\\u6597 - \\u77f3\\u82f1 (SQZ) - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#primaryimage\"},\"datePublished\":\"2022-01-13T15:30:03+00:00\",\"dateModified\":\"2022-01-13T15:30:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\"},\"description\":\"\\u7f8e\\u56fdCharles Supper\\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668\\uff0c\\u8d85\\u5927\\u6bdb\\u7ec6\\u7ba1\\u5b58\\u50a8\\u5bb9\\u5668\\uff0c\\u8fd9\\u4e9b\\u662f\\u7a7a\\u7684\\u73bb\\u7483\\u5bb9\\u5668\\uff0c\\u7528\\u4e8e\\u5bb9\\u7eb3\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u4ee5\\u8fdb\\u884c\\u5b58\\u50a8\\u548c\\u8fd0\\u8f93\\u3002\\u6bcf\\u4e2a\\u5305\\u88c52\\u4e2a\\u5bb9\\u5668\\u8d85\\u5927\\u578b\\u5bb9\\u5668\\u5c06\\u5bb9\\u7eb3\\u5916\\u5f84\\u4e3a3.0mm\\u81f35.0mm\\u7684\\u6bdb\\u7ec6\\u7ba1\\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fdCharles Supper \\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u4e24\\u7aef\\u5f00\\u53e3\\uff0c\\u65e0\\u6f0f\\u6597 &#8211; \\u77f3\\u82f1 (SQZ)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\",\"name\":\"\\u9500\\u552e\\u7ecf\\u7406\\uff1a\\u6768\\u5a771015\\uff0817740862043\\u5fae\\u4fe1\\u540c\\u53f7\\uff09\",\"description\":\"\\u7535\\u8bdd\\uff1a400-840-1510\\u8f6c1005 \\u624b\\u673a\\uff1a177-40862043 \\u4f20\\u771f\\uff1a021-51062822 Email\\uff1a1015@bihec.com QQ:3319485260\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 - \u77f3\u82f1 (SQZ) - Charles Supper\u6bdb\u7ec6\u7ba1","description":"\u7f8e\u56fdCharles Supper\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8d85\u5927\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8fd9\u4e9b\u662f\u7a7a\u7684\u73bb\u7483\u5bb9\u5668\uff0c\u7528\u4e8e\u5bb9\u7eb3\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4ee5\u8fdb\u884c\u5b58\u50a8\u548c\u8fd0\u8f93\u3002\u6bcf\u4e2a\u5305\u88c52\u4e2a\u5bb9\u5668\u8d85\u5927\u578b\u5bb9\u5668\u5c06\u5bb9\u7eb3\u5916\u5f84\u4e3a3.0mm\u81f35.0mm\u7684\u6bdb\u7ec6\u7ba1\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1-sqz\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 - \u77f3\u82f1 (SQZ) - Charles Supper\u6bdb\u7ec6\u7ba1","og_description":"\u7f8e\u56fdCharles Supper\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8d85\u5927\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8fd9\u4e9b\u662f\u7a7a\u7684\u73bb\u7483\u5bb9\u5668\uff0c\u7528\u4e8e\u5bb9\u7eb3\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4ee5\u8fdb\u884c\u5b58\u50a8\u548c\u8fd0\u8f93\u3002\u6bcf\u4e2a\u5305\u88c52\u4e2a\u5bb9\u5668\u8d85\u5927\u578b\u5bb9\u5668\u5c06\u5bb9\u7eb3\u5916\u5f84\u4e3a3.0mm\u81f35.0mm\u7684\u6bdb\u7ec6\u7ba1\u3002","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper-\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597-\u77f3\u82f1-sqz\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","article_published_time":"2022-01-13T15:30:03+00:00","og_image":[{"width":295,"height":205,"url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png","contentUrl":"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2022\/01\/img_61dfccbfa16f6.png","width":295,"height":205},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/","name":"\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 - \u77f3\u82f1 (SQZ) - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#primaryimage"},"datePublished":"2022-01-13T15:30:03+00:00","dateModified":"2022-01-13T15:30:03+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06"},"description":"\u7f8e\u56fdCharles Supper\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8d85\u5927\u6bdb\u7ec6\u7ba1\u5b58\u50a8\u5bb9\u5668\uff0c\u8fd9\u4e9b\u662f\u7a7a\u7684\u73bb\u7483\u5bb9\u5668\uff0c\u7528\u4e8e\u5bb9\u7eb3\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4ee5\u8fdb\u884c\u5b58\u50a8\u548c\u8fd0\u8f93\u3002\u6bcf\u4e2a\u5305\u88c52\u4e2a\u5bb9\u5668\u8d85\u5927\u578b\u5bb9\u5668\u5c06\u5bb9\u7eb3\u5916\u5f84\u4e3a3.0mm\u81f35.0mm\u7684\u6bdb\u7ec6\u7ba1\u3002","breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper-%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e4%b8%a4%e7%ab%af%e5%bc%80%e5%8f%a3%ef%bc%8c%e6%97%a0%e6%bc%8f%e6%96%97-%e7%9f%b3%e8%8b%b1-sqz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fdCharles Supper \u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u4e24\u7aef\u5f00\u53e3\uff0c\u65e0\u6f0f\u6597 &#8211; \u77f3\u82f1 (SQZ)"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06","name":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","description":"\u7535\u8bdd\uff1a400-840-1510\u8f6c1005 \u624b\u673a\uff1a177-40862043 \u4f20\u771f\uff1a021-51062822 Email\uff1a1015@bihec.com QQ:3319485260"}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752606"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/comments?post=752606"}],"version-history":[{"count":1,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752606\/revisions"}],"predecessor-version":[{"id":752607,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752606\/revisions\/752607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media\/752595"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media?parent=752606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories?post=752606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/tags?post=752606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}