﻿{"id":752544,"date":"2022-01-13T11:50:47","date_gmt":"2022-01-13T03:50:47","guid":{"rendered":"https:\/\/www.bihec.com\/charles-supper\/?p=752544"},"modified":"2022-01-13T11:50:47","modified_gmt":"2022-01-13T03:50:47","slug":"%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/","title":{"rendered":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68"},"content":{"rendered":"<p><strong>Charles Supper\u00a0 \u516c\u53f8\u00a0 <a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa\/\" title=\"View all posts in \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\" target=\"_blank\">\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea<\/a>\uff0c<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8\/\" title=\"View all posts in X-Y\u5fae\u578b\u6ed1\u8f68\" target=\"_blank\">X-Y\u5fae\u578b\u6ed1\u8f68<\/a><br \/>\n<\/strong><\/p>\n<hr \/>\n<p>\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea<\/p>\n<p>Charles Supper\u516c\u53f8\u7684<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e5%be%ae%e5%9e%8b%e5%ae%9a%e4%bd%8d%e5%99%a8\/\" title=\"View all posts in \u5fae\u578b\u5b9a\u4f4d\u5668\" target=\"_blank\">\u5fae\u578b\u5b9a\u4f4d\u5668<\/a>\u662f\u76ee\u524d\u53ef\u7528\u4e8e<\/p>\n<p>\u6267\u884c\u7cbe\u786e\u624b\u52a8\u8c03\u6574\u7684\u6700\u5c0f\u548c\u6700\u591a\u6837\u5316\u7684\u6807\u51c6\u4ea7\u54c1\u7ec4\u3002<img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg\" \/><\/p>\n<p>\u5b83\u4eec\u53ef\u4ee5\u8bbe\u8ba1\u6210\u65b0\u7684\u4eea\u5668\u548c\u7ec4\u4ef6\uff0c<\/p>\n<p>\u4e5f\u53ef\u4ee5\u5f88\u5bb9\u6613\u5730\u6539\u88c5\u6210\u73b0\u6709\u7684\u4eea\u5668\u548c\u7ec4\u4ef6\u3002<\/p>\n<p>\u5f53\u5fae\u5c0f\u5c3a\u5bf8\u3001\u7a33\u5b9a\u6027\u548c\u5fae\u8c03\u81f3\u5173\u91cd\u8981\u65f6\uff0c<\/p>\n<p>Charles Supper\u516c\u53f8\u7684\u5fae\u5b9a\u4f4d\u4eea\u5c06\u4e3a\u533b\u7597\u3001\u5149\u5b66\u3001\u5149\u7535\u3001\u6fc0\u5149\u3001<\/p>\n<p>\u6444\u5f71\u548c\u76f8\u5173\u9886\u57df\u7684\u8bb8\u591a\u5e94\u7528\u63d0\u4f9b\u4fbf\u5229\u3002<\/p>\n<p>\u5b83\u4eec\u975e\u5e38\u9002\u5408\u8bbe\u8ba1\u6210\u65b0\u7684\u5939\u5177\u548c\u7ec4\u4ef6\uff0c\u5e76\u4e14\u5f88\u5bb9\u6613\u9002\u5e94\u73b0\u6709\u7684\u7ec4\u4ef6\u3002<\/p>\n<p>\u4e3b\u8981\u7279\u70b9<img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.charles-supper.com\/images\/esq-2201.png\" \/><\/p>\n<p>\u5141\u8bb8\u5fae\u8c03\u5b9a\u4f4d\u3002<br \/>\n\u8010\u7528\u7684\u94dd\u5236\u7ed3\u6784\uff0c\u5e26\u6709\u786c\u5316\u4e0d\u9508\u94a2\u9a71\u52a8\u87ba\u9489\u548c\u6c38\u4e45\u6da6\u6ed1\u3002<br \/>\n\u914d\u67091\/16\u201c\u82b1\u952e\u9a71\u52a8\u952e\uff0c\u7528\u4e8e\u8c03\u6574\u548c\u9501\u5b9a\u6bcf\u4e2a\u8fd0\u52a8\u5230\u4f4d\u3002<br \/>\n\u94bb\u5b54\u548c\u87ba\u7eb9\u5b54\u7528\u4e8e\u591a\u79cd\u5b89\u88c5\u5e03\u7f6e\u3002<br \/>\nX-Y\u5fae\u578b\u5e7b\u706f\u7247\u6709\u56db\u79cd\u5c3a\u5bf8\uff0c<br \/>\n\u4ece0.844&#8243; O.D. \uff08X-Y\u884c\u7a0b\u4e3a0.250&#8243;\uff09\u52301.487&#8243; O.D. \uff08X-Y\u884c\u7a0b\u4e3a0.3125&#8243;\uff09\uff0c<br \/>\n\u6bcf\u4e2a\u5e73\u79fb\u5e95\u5ea7\u53ef\u4ee5\u5b8c\u5168\u9501\u5b9a\u3002<br \/>\n\u5bf9\u4e8e\u5b89\u88c5\uff0c\u4e00\u4e2a\u96ea\u6a47\u6709\u4e24\u4e2a\u94bb\u5b54\u548c\u87ba\u7eb9\u5b54\uff0c<br \/>\n\u7b2c\u4e8c\u4e2a\u96ea\u6a47\u6709\u4e24\u4e2a\u5728\u5185\u4fa7\u57cb\u5934\u5b54\u3002<br \/>\n\u76ee\u5f55#2201 X-Y\u5fae\u578b\u5e7b\u706f\u7247<br \/>\n\u5916\u5f84935<br \/>\n\u539a\u5ea6330<br \/>\n\u6bcf\u4e2a\u8f74\u7684\u6700\u5927\u884c\u7a0b250<br \/>\n\u4e1d\u6760\u87ba\u7eb94-40<\/p>\n<p><audio controls=\"controls\"><\/audio><\/p>\n<div id=\"qb-sougou-search\">\n<p>\u641c\u7d22<\/p>\n<p class=\"last-btn\">\u590d\u5236<\/p>\n<\/div>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/360o-%e5%be%ae%e6%97%8b%e8%bd%ac%e5%8f%b0\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 8pt;\" aria-label=\"360\u00ba \u5fae\u65cb\u8f6c\u53f0 (10\u4e2a\u9879\u76ee)\">360\u00ba \u5fae\u65cb\u8f6c\u53f0<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 11.5pt;\" aria-label=\"X-Y\u5fae\u578b\u6ed1\u8f68 (19\u4e2a\u9879\u76ee)\">X-Y\u5fae\u578b\u6ed1\u8f68<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 22pt;\" aria-label=\"X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1 (118\u4e2a\u9879\u76ee)\">X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%a0%87%e5%87%86%e6%b5%8b%e8%a7%92%e5%a4%b4\/\" class=\"tag-cloud-link tag-link-3 tag-link-position-4\" style=\"font-size: 14.326923076923pt;\" aria-label=\"\u6807\u51c6\u6d4b\u89d2\u5934 (31\u4e2a\u9879\u76ee)\">\u6807\u51c6\u6d4b\u89d2\u5934<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa\/\" class=\"tag-cloud-link tag-link-4 tag-link-position-5\" style=\"font-size: 8.9423076923077pt;\" aria-label=\"\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea (12\u4e2a\u9879\u76ee)\">\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Charles Supper\u00a0 \u516c\u53f8\u00a0 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea Charles Supper\u516c\u53f8\u7684\u5fae\u578b\u5b9a\u4f4d\u5668\u662f\u76ee\u524d\u53ef\u7528\u4e8e \u6267\u884c\u7cbe\u786e\u624b\u52a8\u8c03\u6574\u7684\u6700\u5c0f\u548c\u6700\u591a\u6837\u5316\u7684\u6807\u51c6 <\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[3,36,37],"tags":[35,38,6,26,39],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cx-y\u5fae\u578b\u6ed1\u8f68-6\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:description\" content=\"Charles Supper\u00a0 \u516c\u53f8\u00a0 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea Charles Supper\u516c\u53f8\u7684\u5fae\u578b\u5b9a\u4f4d\u5668\u662f\u76ee\u524d\u53ef\u7528\u4e8e \u6267\u884c\u7cbe\u786e\u624b\u52a8\u8c03\u6574\u7684\u6700\u5c0f\u548c\u6700\u591a\u6837\u5316\u7684\u6807\u51c6\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cx-y\u5fae\u578b\u6ed1\u8f68-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-13T03:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg\",\"contentUrl\":\"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/\",\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u7cbe\\u5bc6\\u5fae\\u5b9a\\u4f4d\\u4eea\\uff0cX-Y\\u5fae\\u578b\\u6ed1\\u8f68 - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#primaryimage\"},\"datePublished\":\"2022-01-13T03:50:47+00:00\",\"dateModified\":\"2022-01-13T03:50:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u7cbe\\u5bc6\\u5fae\\u5b9a\\u4f4d\\u4eea\\uff0cX-Y\\u5fae\\u578b\\u6ed1\\u8f68\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\",\"name\":\"\\u9500\\u552e\\u7ecf\\u7406\\uff1a\\u6768\\u5a771015\\uff0817740862043\\u5fae\\u4fe1\\u540c\\u53f7\\uff09\",\"description\":\"\\u7535\\u8bdd\\uff1a400-840-1510\\u8f6c1005 \\u624b\\u673a\\uff1a177-40862043 \\u4f20\\u771f\\uff1a021-51062822 Email\\uff1a1015@bihec.com QQ:3319485260\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 - Charles Supper\u6bdb\u7ec6\u7ba1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cx-y\u5fae\u578b\u6ed1\u8f68-6\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 - Charles Supper\u6bdb\u7ec6\u7ba1","og_description":"Charles Supper\u00a0 \u516c\u53f8\u00a0 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 \u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea Charles Supper\u516c\u53f8\u7684\u5fae\u578b\u5b9a\u4f4d\u5668\u662f\u76ee\u524d\u53ef\u7528\u4e8e \u6267\u884c\u7cbe\u786e\u624b\u52a8\u8c03\u6574\u7684\u6700\u5c0f\u548c\u6700\u591a\u6837\u5316\u7684\u6807\u51c6","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cx-y\u5fae\u578b\u6ed1\u8f68-6\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","article_published_time":"2022-01-13T03:50:47+00:00","og_image":[{"url":"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg","contentUrl":"https:\/\/www.charles-supper.com\/product\/images\/product_00019_00040.jpg"},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/","name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68 - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#primaryimage"},"datePublished":"2022-01-13T03:50:47+00:00","dateModified":"2022-01-13T03:50:47+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06"},"breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e7%b2%be%e5%af%86%e5%be%ae%e5%ae%9a%e4%bd%8d%e4%bb%aa%ef%bc%8cx-y%e5%be%ae%e5%9e%8b%e6%bb%91%e8%bd%a8-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u7cbe\u5bc6\u5fae\u5b9a\u4f4d\u4eea\uff0cX-Y\u5fae\u578b\u6ed1\u8f68"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06","name":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","description":"\u7535\u8bdd\uff1a400-840-1510\u8f6c1005 \u624b\u673a\uff1a177-40862043 \u4f20\u771f\uff1a021-51062822 Email\uff1a1015@bihec.com QQ:3319485260"}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752544"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/comments?post=752544"}],"version-history":[{"count":2,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752544\/revisions"}],"predecessor-version":[{"id":752578,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752544\/revisions\/752578"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media?parent=752544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories?post=752544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/tags?post=752544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}