﻿{"id":752465,"date":"2021-06-21T15:35:04","date_gmt":"2021-06-21T07:35:04","guid":{"rendered":"https:\/\/www.bihec.com\/charles-supper\/?p=752465"},"modified":"2021-06-21T15:54:10","modified_gmt":"2021-06-21T07:54:10","slug":"%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6","status":"publish","type":"post","link":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/","title":{"rendered":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934"},"content":{"rendered":"<p><strong>Charles Supper\u00a0 \u516c\u53f8\u751f\u4ea7<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%b5%8b%e8%a7%92%e4%bb%aa\/\" title=\"View all posts in \u6d4b\u89d2\u4eea\" target=\"_blank\">\u6d4b\u89d2\u4eea<\/a>\u5934\u5df2\u6709\u534a\u4e2a\u591a\u4e16\u7eaa\u4e86\u3002\u8fd9\u4e9b\u4eea\u5668\u7684\u8bbe\u8ba1\u8d28\u91cf\u3001\u5de5\u827a\u548c\u7ec6\u8282\u90fd\u8fbe\u5230\u4e86\u6700\u9ad8\u6807\u51c6\u3002<\/strong><\/p>\n<hr \/>\n<p>\u8d85\u6d4b\u89d2\u5934\u662f\u4e00\u79cd\u7cbe\u5bc6\u3001\u8d85\u7a33\u5b9a\u7684\u6676\u4f53\u6837\u54c1\u5b89\u88c5\u4eea\u5668\u3002<img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg\" \/><br \/>\n\u5b83\u4eec\u6ca1\u6709\u53cd\u4f5c\u7528\u529b\uff0c\u4f46\u8fd0\u52a8\u5e73\u7a33\u3002\u5f27\u7ebf\u4ee5\u6c34\u6676\u4e3a\u4e2d\u5fc3\u3002\u6240\u6709\u7684\u52a8\u4f5c\u90fd\u662f\u5b8c\u5168\u9501\u5b9a\u7684\uff0c\u4ee5\u9632\u6b62\u6c34\u6676\u6ed1\u843d\u3002\u89d2\u5b9a\u4f4d\u662f\u901a\u8fc7\u4f7f\u7528\u51f9\u8fdb\u7684\u87ba\u65cb\u9972\u6599\uff0c\u4ee5\u5bfc\u81f4\u786c\u5316\u4e0d\u9508\u94a2\u87ba\u9489\u3002\u7528\u6e38\u6807\u5361\u5c3a\u5c06\u5f27\u7684\u4f4d\u7f6e\u8bfb\u52305\u5206\u949f\u3002<\/p>\n<p>\u6211\u4eec\u7684\u6d4b\u89d2\u5934\u7b26\u5408ACA\/IUC\u6807\u51c6\uff0c\u5e76\u4e0e\u6700\u65b0\u7684X\u5c04\u7ebf\u6676\u4f53\u5b66\u8bbe\u5907\u517c\u5bb9\u3002<\/p>\n<p><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%a0%87%e5%87%86%e6%b5%8b%e8%a7%92%e5%a4%b4\/\" title=\"View all posts in \u6807\u51c6\u6d4b\u89d2\u5934\" target=\"_blank\">\u6807\u51c6\u6d4b\u89d2\u5934<\/a>\u89c4\u8303<\/p>\n<p>\u8ddd\u5f27\u4e2d\u5fc363.97mm\u9ad8<\/p>\n<p>\u7531\u4e0d\u9508\u94a2\u548c\u94dd\u5236\u6210<\/p>\n<p>\u6dec\u706b\u94a2\u4f20\u52a8\u87ba\u9489<\/p>\n<p id=\"mfWJWiT\"><img decoding=\"async\" loading=\"lazy\" width=\"263\" height=\"232\" class=\"size-full wp-image-752474 alignright\" src=\"https:\/\/www.bihec.com\/charles-supper\/wp-content\/uploads\/sites\/275\/2021\/06\/img_60d04364ed8a0.png\" alt=\"\" \/><\/p>\n<p>\u5e73\u7a33\u7684\u52a8\u4f5c<\/p>\n<p>\u542b\u65b9\u5957\u7b52\u8c03\u8282\u6273\u624b<\/p>\n<p>\u8d85\u8fc7290\u00ba \u6676\u4f53\u5468\u56f4\u95f4\u9699<\/p>\n<p>X-Y\u79fb\u52a8\u6bcf\u4e2a\u8f74\u3002750<\/p>\n<p>\u5c0f\u5f27\u884c\u7a0b+-26\u00ba<\/p>\n<p>\u5927\u5f27\u884c\u7a0b+-24\u00ba<\/p>\n<p>\u4ece\u9876\u90e8\u5b89\u88c5\u5230\u5f27\u4e2d\u5fc313mm\u9ad8<\/p>\n<p>\u4f7f\u7528\u6807\u51c61\/8\u201c\u8bd5\u6837\u5b89\u88c5\u9500<\/p>\n<p>ACA\/IUC\u6807\u51c6\u914d\u4ef6<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<br><div class=\"tagcloud\"><a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/x%e5%b0%84%e7%ba%bf%e8%a1%8d%e5%b0%84%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-0 tag-link-position-1\" style=\"font-size: 22pt;\" aria-label=\"X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1 (118\u4e2a\u9879\u76ee)\">X\u5c04\u7ebf\u884d\u5c04\u8584\u58c1\u6bdb\u7ec6\u7ba1<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%a0%87%e5%87%86%e6%b5%8b%e8%a7%92%e5%a4%b4\/\" class=\"tag-cloud-link tag-link-1 tag-link-position-2\" style=\"font-size: 8pt;\" aria-label=\"\u6807\u51c6\u6d4b\u89d2\u5934 (31\u4e2a\u9879\u76ee)\">\u6807\u51c6\u6d4b\u89d2\u5934<\/a>\n<a href=\"https:\/\/www.bihec.com\/charles-supper\/tag\/%e6%af%9b%e7%bb%86%e7%ae%a1\/\" class=\"tag-cloud-link tag-link-2 tag-link-position-3\" style=\"font-size: 21.263157894737pt;\" aria-label=\"\u6bdb\u7ec6\u7ba1 (112\u4e2a\u9879\u76ee)\">\u6bdb\u7ec6\u7ba1<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Charles Supper\u00a0 \u516c\u53f8\u751f\u4ea7\u6d4b\u89d2\u4eea\u5934\u5df2\u6709\u534a\u4e2a\u591a\u4e16\u7eaa\u4e86\u3002\u8fd9\u4e9b\u4eea\u5668\u7684\u8bbe\u8ba1\u8d28\u91cf\u3001\u5de5\u827a\u548c\u7ec6\u8282\u90fd\u8fbe\u5230\u4e86\u6700\u9ad8\u6807\u51c6\u3002 \u8d85\u6d4b\u89d2\u5934\u662f\u4e00\u79cd\u7cbe\u5bc6\u3001\u8d85\u7a33\u5b9a\u7684\u6676\u4f53\u6837\u54c1\u5b89\u88c5\u4eea\u5668\u3002 \u5b83\u4eec\u6ca1\u6709\u53cd\u4f5c\u7528\u529b <\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[3,25],"tags":[6,26,5],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934 - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u900f\u660e\u5bc6\u5c01\u5e26\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934 - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:description\" content=\"Charles Supper\u00a0 \u516c\u53f8\u751f\u4ea7\u6d4b\u89d2\u4eea\u5934\u5df2\u6709\u534a\u4e2a\u591a\u4e16\u7eaa\u4e86\u3002\u8fd9\u4e9b\u4eea\u5668\u7684\u8bbe\u8ba1\u8d28\u91cf\u3001\u5de5\u827a\u548c\u7ec6\u8282\u90fd\u8fbe\u5230\u4e86\u6700\u9ad8\u6807\u51c6\u3002 \u8d85\u6d4b\u89d2\u5934\u662f\u4e00\u79cd\u7cbe\u5bc6\u3001\u8d85\u7a33\u5b9a\u7684\u6676\u4f53\u6837\u54c1\u5b89\u88c5\u4eea\u5668\u3002 \u5b83\u4eec\u6ca1\u6709\u53cd\u4f5c\u7528\u529b\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u900f\u660e\u5bc6\u5c01\u5e26\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T07:35:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-21T07:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#primaryimage\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg\",\"contentUrl\":\"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/\",\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u6807\\u51c6\\u6d4b\\u89d2\\u5934 - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#primaryimage\"},\"datePublished\":\"2021-06-21T07:35:04+00:00\",\"dateModified\":\"2021-06-21T07:54:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7f8e\\u56fdCharles Supper\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\\uff0c\\u6807\\u51c6\\u6d4b\\u89d2\\u5934\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06\",\"name\":\"\\u9500\\u552e\\u7ecf\\u7406\\uff1a\\u6768\\u5a771015\\uff0817740862043\\u5fae\\u4fe1\\u540c\\u53f7\\uff09\",\"description\":\"\\u7535\\u8bdd\\uff1a400-840-1510\\u8f6c1005 \\u624b\\u673a\\uff1a177-40862043 \\u4f20\\u771f\\uff1a021-51062822 Email\\uff1a1015@bihec.com QQ:3319485260\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934 - Charles Supper\u6bdb\u7ec6\u7ba1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u900f\u660e\u5bc6\u5c01\u5e26\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934 - Charles Supper\u6bdb\u7ec6\u7ba1","og_description":"Charles Supper\u00a0 \u516c\u53f8\u751f\u4ea7\u6d4b\u89d2\u4eea\u5934\u5df2\u6709\u534a\u4e2a\u591a\u4e16\u7eaa\u4e86\u3002\u8fd9\u4e9b\u4eea\u5668\u7684\u8bbe\u8ba1\u8d28\u91cf\u3001\u5de5\u827a\u548c\u7ec6\u8282\u90fd\u8fbe\u5230\u4e86\u6700\u9ad8\u6807\u51c6\u3002 \u8d85\u6d4b\u89d2\u5934\u662f\u4e00\u79cd\u7cbe\u5bc6\u3001\u8d85\u7a33\u5b9a\u7684\u6676\u4f53\u6837\u54c1\u5b89\u88c5\u4eea\u5668\u3002 \u5b83\u4eec\u6ca1\u6709\u53cd\u4f5c\u7528\u529b","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u7f8e\u56fdcharles-supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u900f\u660e\u5bc6\u5c01\u5e26\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","article_published_time":"2021-06-21T07:35:04+00:00","article_modified_time":"2021-06-21T07:54:10+00:00","og_image":[{"url":"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"ImageObject","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#primaryimage","inLanguage":"zh-CN","url":"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg","contentUrl":"https:\/\/www.charles-supper.com\/product\/images\/product_00022_00042.jpg"},{"@type":"WebPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/","name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934 - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#primaryimage"},"datePublished":"2021-06-21T07:35:04+00:00","dateModified":"2021-06-21T07:54:10+00:00","author":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06"},"breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e7%be%8e%e5%9b%bdcharles-supper%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1%ef%bc%8c%e9%80%8f%e6%98%8e%e5%af%86%e5%b0%81%e5%b8%a6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u7f8e\u56fdCharles Supper\u8584\u58c1\u6bdb\u7ec6\u7ba1\uff0c\u6807\u51c6\u6d4b\u89d2\u5934"}]},{"@type":"Person","@id":"https:\/\/www.bihec.com\/charles-supper\/#\/schema\/person\/5d609f69c7b9fc4ae4f05a203e5c4e06","name":"\u9500\u552e\u7ecf\u7406\uff1a\u6768\u5a771015\uff0817740862043\u5fae\u4fe1\u540c\u53f7\uff09","description":"\u7535\u8bdd\uff1a400-840-1510\u8f6c1005 \u624b\u673a\uff1a177-40862043 \u4f20\u771f\uff1a021-51062822 Email\uff1a1015@bihec.com QQ:3319485260"}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752465"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/comments?post=752465"}],"version-history":[{"count":2,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752465\/revisions"}],"predecessor-version":[{"id":752478,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts\/752465\/revisions\/752478"}],"wp:attachment":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/media?parent=752465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories?post=752465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/tags?post=752465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}