﻿{"id":99,"count":1,"description":"","link":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/","name":"Quartz 40-QZ - 4.0mm","slug":"quartz-40-qz-4-0mm","taxonomy":"category","parent":83,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quartz 40-QZ - 4.0mm \u5f52\u6863 - Charles Supper\u6bdb\u7ec6\u7ba1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bihec.com\/charles-supper\/\u8584\u58c1\u6bdb\u7ec6\u7ba1\/\u77f3\u82f1\/quartz-40-qz-4-0mm\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quartz 40-QZ - 4.0mm \u5f52\u6863 - Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bihec.com\/charles-supper\/\u8584\u58c1\u6bdb\u7ec6\u7ba1\/\u77f3\u82f1\/quartz-40-qz-4-0mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Supper\u6bdb\u7ec6\u7ba1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/\",\"name\":\"Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#webpage\",\"url\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/\",\"name\":\"Quartz 40-QZ - 4.0mm \\u5f52\\u6863 - Charles Supper\\u6bdb\\u7ec6\\u7ba1\",\"isPartOf\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9875\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u8584\\u58c1\\u6bdb\\u7ec6\\u7ba1\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\\u77f3\\u82f1\",\"item\":\"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quartz 40-QZ - 4.0mm\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quartz 40-QZ - 4.0mm \u5f52\u6863 - Charles Supper\u6bdb\u7ec6\u7ba1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bihec.com\/charles-supper\/\u8584\u58c1\u6bdb\u7ec6\u7ba1\/\u77f3\u82f1\/quartz-40-qz-4-0mm\/","og_locale":"zh_CN","og_type":"article","og_title":"Quartz 40-QZ - 4.0mm \u5f52\u6863 - Charles Supper\u6bdb\u7ec6\u7ba1","og_url":"https:\/\/www.bihec.com\/charles-supper\/\u8584\u58c1\u6bdb\u7ec6\u7ba1\/\u77f3\u82f1\/quartz-40-qz-4-0mm\/","og_site_name":"Charles Supper\u6bdb\u7ec6\u7ba1","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bihec.com\/charles-supper\/#website","url":"https:\/\/www.bihec.com\/charles-supper\/","name":"Charles Supper\u6bdb\u7ec6\u7ba1","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bihec.com\/charles-supper\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"CollectionPage","@id":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#webpage","url":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/","name":"Quartz 40-QZ - 4.0mm \u5f52\u6863 - Charles Supper\u6bdb\u7ec6\u7ba1","isPartOf":{"@id":"https:\/\/www.bihec.com\/charles-supper\/#website"},"breadcrumb":{"@id":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/quartz-40-qz-4-0mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.bihec.com\/charles-supper\/"},{"@type":"ListItem","position":2,"name":"\u8584\u58c1\u6bdb\u7ec6\u7ba1","item":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/"},{"@type":"ListItem","position":3,"name":"\u77f3\u82f1","item":"https:\/\/www.bihec.com\/charles-supper\/%e8%96%84%e5%a3%81%e6%af%9b%e7%bb%86%e7%ae%a1\/%e7%9f%b3%e8%8b%b1\/"},{"@type":"ListItem","position":4,"name":"Quartz 40-QZ - 4.0mm"}]}]}},"_links":{"self":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories\/99"}],"collection":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/categories\/83"}],"wp:post_type":[{"href":"https:\/\/www.bihec.com\/charles-supper\/wp-json\/wp\/v2\/posts?categories=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}